{"id":186970,"date":"2026-01-15T19:02:34","date_gmt":"2026-01-15T18:02:34","guid":{"rendered":"https:\/\/sex-3.de\/shop\/shop\/secretplay-lipgloss-vibrant-kiss-pina-colada\/"},"modified":"2026-01-19T09:42:55","modified_gmt":"2026-01-19T08:42:55","slug":"secretplay-lipgloss-vibrant-kiss-pina-colada","status":"publish","type":"product","link":"https:\/\/sex-3.de\/shop\/shop\/secretplay-lipgloss-vibrant-kiss-pina-colada\/","title":{"rendered":"SECRETPLAY &#8211; LIPGLOSS VIBRANT KISS ? PINA COLADA"},"content":{"rendered":"<p>Haben Sie schon einmal einen Lipgloss gesehen, der Vibrationswellen erzeugt? Haben Sie jemals gedacht, dass ein Lipgloss in Ihr Leben kommen w&uuml;rde und Ihnen noch mehr Freude am Oralsex und K&uuml;ssen bereiten w&uuml;rde?<\/p>\n<p>Mit dem Lipgloss Vibrant Kiss Strawberry Gum Geschmack k&ouml;nnen Sie f&uuml;r sich und Ihren Liebhaber unvorstellbare Lustgef&uuml;hle erleben. Seine Vibrationswellen erzeugen ein angenehmes Kribbeln, das zur Stimulation Ihrer Sinne beitr&auml;gt und die Sensibilit&auml;t und das Vergn&uuml;gen steigert. Es kann beim Oralsex oder einfach zum K&uuml;ssen verwendet werden. Vergn&uuml;gen zu zweit.<\/p>\n<ul>\n<li>Verpackung: 6 gr<\/li>\n<li>Geschmack: Pi&ntilde;a Colada<\/li>\n<li>100 % essbar<\/li>\n<li>Glycerinbasis<\/li>\n<li>Kompatibel mit Kondomen und Spielzeugen<\/li>\n<li>Vor Gebrauch sch&uuml;tteln<\/li>\n<li>100 % tierversuchsfrei<\/li>\n<li>Hergestellt in Spanien<\/li>\n<\/ul>\n<p>Referenz: 3687<\/p>\n<ul>\n<li>EAN: 8435097836878<\/li>\n<li>Gewicht: 0,02 kg \/ 20 g<\/li>\n<li>Ma&szlig;e: 2 (&Oslash;) (Durchmesser) x 10 (H&ouml;he)<\/li>\n<\/ul>\n<p>Zutaten:<br \/>Aromatisierte, zuckerhaltige und ges&uuml;&szlig;te Pi&ntilde;a Colada.<br \/>Pi&ntilde;a-Colada-Sirup (Zucker, Wasser, nat&uuml;rliches Kokosaroma, Zitronensaftkonzentrat, Emulgatoren Gummi Arabicum, E445, Farbstoff E161B, Fruchtsaft 23 %, mit 11 % Ananassaft), Glycerin E422, Acmella Oleracea-Extrakt, Farbstoff E102, Stabilisator E415, Konservierungsmittel E202, Feuchtigkeitscreme E1520.<\/p>\n<ul>\n<li>N&auml;hrwert: 935 KJ\/ 224 Kcal<\/li>\n<li>Fette\/ges&auml;ttigte Fetts&auml;uren: 0,07 g\/0 g<\/li>\n<li>Kohlenhydrate\/Zucker: 54,7g\/54,6g<\/li>\n<li>Proteine: 0,07g<\/li>\n<li>Salz: 0,02g<\/li>\n<\/ul>\n<p>Wie benutzt man:<br \/>Tragen Sie es auf die Lippen auf und in wenigen Sekunden werden Sie eine stimulierende Vibration sp&uuml;ren.<\/p>\n<p>Vorsichtsma&szlig;nahmen:<br \/>&#8211; Vor Gebrauch sch&uuml;tteln.<br \/>&#8211; Nicht anwenden bei &Uuml;berempfindlichkeit oder Allergie gegen einen der Inhaltsstoffe.<br \/>-Bei Reizungen die Anwendung abbrechen.<br \/>&#8211; Nicht auf die Augenpartie oder auf Wunden auftragen.<br \/>-Nicht einnehmen.<br \/>&#8211; Au&szlig;erhalb der Reichweite von Kindern aufbewahren.<br \/>&#8211; An einem k&uuml;hlen und trockenen Ort aufbewahren und vor Sonnenlicht sch&uuml;tzen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haben Sie schon einmal einen Lipgloss gesehen, der Vibrationswellen erzeugt? Haben Sie jemals gedacht, dass ein Lipgloss in Ihr Leben kommen w&uuml;rde und Ihnen noch mehr Freude am Oralsex und K&uuml;ssen bereiten w&uuml;rde? Mit dem Lipgloss Vibrant Kiss Strawberry Gum Geschmack k&ouml;nnen Sie f&uuml;r sich und Ihren Liebhaber unvorstellbare Lustgef&uuml;hle erleben. Seine Vibrationswellen erzeugen ein<\/p>\n<div class=\"more-link\">\n\t\t\t\t <a href=\"https:\/\/sex-3.de\/shop\/shop\/secretplay-lipgloss-vibrant-kiss-pina-colada\/\" class=\"btn theme-btn\"><span>Weiterlesen <\/span><i class=\"icofont-thin-double-right\"><\/i><\/a>\n\t\t\t<\/div>\n","protected":false},"featured_media":100441,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[1251,1366],"product_tag":[],"class_list":["post-186970","product","type-product","status-publish","has-post-thumbnail","product_cat-drogerie","product_cat-fuer-oralsex","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/product\/186970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/comments?post=186970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/media\/100441"}],"wp:attachment":[{"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/media?parent=186970"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/product_brand?post=186970"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/product_cat?post=186970"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sex-3.de\/shop\/wp-json\/wp\/v2\/product_tag?post=186970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}